{"id":26095,"date":"2024-11-22T16:40:47","date_gmt":"2024-11-22T14:40:47","guid":{"rendered":"https:\/\/dakauf.fi\/en\/?post_type=product&#038;p=26095"},"modified":"2025-07-05T18:05:37","modified_gmt":"2025-07-05T15:05:37","slug":"braun-oral-b-pro-700-floss-action-electric-toothbrush-blue-white","status":"publish","type":"product","link":"https:\/\/dakauf.fi\/fi\/product\/braun-oral-b-pro-700-floss-action-electric-toothbrush-blue-white\/","title":{"rendered":"Braun Oral-B Pro 700 Floss Action Electric Toothbrush Blue\/White"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><span class=\"success-color\">\u2714<\/span>Target group: Adults<br \/>\n<span class=\"success-color\">\u2714<\/span>Toothbrush type: Oscillating toothbrush<br \/>\n<span class=\"success-color\">\u2714<\/span>Number of levels: 1 x<br \/>\n<span class=\"success-color\">\u2714<\/span>Power supply: Battery operated<\/p>\n","protected":false},"featured_media":26097,"template":"","meta":[],"product_cat":[387,388,181],"product_tag":[],"class_list":{"0":"post-26095","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-personal-hygiene","7":"product_cat-electric-toothbrushes","8":"product_cat-home-beauty","10":"first","11":"outofstock","12":"sale","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/dakauf.fi\/fi\/wp-json\/wp\/v2\/product\/26095"}],"collection":[{"href":"https:\/\/dakauf.fi\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dakauf.fi\/fi\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dakauf.fi\/fi\/wp-json\/wp\/v2\/media\/26097"}],"wp:attachment":[{"href":"https:\/\/dakauf.fi\/fi\/wp-json\/wp\/v2\/media?parent=26095"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dakauf.fi\/fi\/wp-json\/wp\/v2\/product_cat?post=26095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dakauf.fi\/fi\/wp-json\/wp\/v2\/product_tag?post=26095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}